{"id":5267,"date":"2020-06-19T14:24:33","date_gmt":"2020-06-19T12:24:33","guid":{"rendered":"http:\/\/www.suorediloreto.it\/lor\/?page_id=5267"},"modified":"2021-01-05T17:09:35","modified_gmt":"2021-01-05T16:09:35","slug":"accoglienza-nelle-nostre-strutture","status":"publish","type":"page","link":"https:\/\/www.suorediloreto.it\/lor\/le-attivita-2\/accoglienza-nelle-nostre-strutture\/","title":{"rendered":"Accoglienza nelle nostre strutture"},"content":{"rendered":"<p>Accogliere, vivere e trasmettere l\u2019Amore per accompagnare la crescita di ciascuno in et\u00e0, sapienza e grazia. (n. 2 Cost.)<\/p>\n<p>Le nostre case sono aperte per accogliere tutti coloro che vogliono ritagliarsi una sosta godendo sia dei benefici del clima marittimo che delle passeggiate tra la natura.<\/p>\n<p>Distensione, riflessione, divertimento e cultura sono il cocktail che noi suore di Loreto, in un clima e con uno stile famigliare, offriremo a tutti coloro che vorranno trascorrere un po\u2019 di tempo nelle nostre case.<\/p>\n<p>Il soggiorno pu\u00f2 essere arricchito da proposte di visite e incontri organizzati oppure lasciato alla libert\u00e0 personale e famigliare.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Accogliere, vivere e trasmettere l\u2019Amore per accompagnare la crescita di ciascuno in et\u00e0, sapienza e grazia. (n. 2 Cost.) Le nostre case sono aperte per accogliere tutti coloro che vogliono ritagliarsi una sosta godendo sia dei benefici del clima marittimo che delle passeggiate tra la natura. Distensione, riflessione, divertimento e cultura sono il cocktail che&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":4820,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ghostkit_customizer_options":"","ghostkit_custom_css":"","ghostkit_custom_js_head":"","ghostkit_custom_js_foot":"","ghostkit_typography":"","_vp_format_video_url":"","_vp_image_focal_point":[],"footnotes":""},"class_list":["post-5267","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Accoglienza nelle nostre strutture - Suore di Loreto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suorediloreto.it\/lor\/le-attivita-2\/accoglienza-nelle-nostre-strutture\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Accoglienza nelle nostre strutture - Suore di Loreto\" \/>\n<meta property=\"og:description\" content=\"Accogliere, vivere e trasmettere l\u2019Amore per accompagnare la crescita di ciascuno in et\u00e0, sapienza e grazia. (n. 2 Cost.) Le nostre case sono aperte per accogliere tutti coloro che vogliono ritagliarsi una sosta godendo sia dei benefici del clima marittimo che delle passeggiate tra la natura. Distensione, riflessione, divertimento e cultura sono il cocktail che...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suorediloreto.it\/lor\/le-attivita-2\/accoglienza-nelle-nostre-strutture\/\" \/>\n<meta property=\"og:site_name\" content=\"Suore di Loreto\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-05T16:09:35+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suorediloreto.it\/lor\/le-attivita-2\/accoglienza-nelle-nostre-strutture\/\",\"url\":\"https:\/\/www.suorediloreto.it\/lor\/le-attivita-2\/accoglienza-nelle-nostre-strutture\/\",\"name\":\"Accoglienza nelle nostre strutture - Suore di Loreto\",\"isPartOf\":{\"@id\":\"https:\/\/www.suorediloreto.it\/lor\/#website\"},\"datePublished\":\"2020-06-19T12:24:33+00:00\",\"dateModified\":\"2021-01-05T16:09:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suorediloreto.it\/lor\/le-attivita-2\/accoglienza-nelle-nostre-strutture\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suorediloreto.it\/lor\/le-attivita-2\/accoglienza-nelle-nostre-strutture\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suorediloreto.it\/lor\/le-attivita-2\/accoglienza-nelle-nostre-strutture\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.suorediloreto.it\/lor\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le attivit\u00e0\",\"item\":\"https:\/\/www.suorediloreto.it\/lor\/le-attivita-2\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Accoglienza nelle nostre strutture\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suorediloreto.it\/lor\/#website\",\"url\":\"https:\/\/www.suorediloreto.it\/lor\/\",\"name\":\"Suore di Loreto\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suorediloreto.it\/lor\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Accoglienza nelle nostre strutture - Suore di Loreto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suorediloreto.it\/lor\/le-attivita-2\/accoglienza-nelle-nostre-strutture\/","og_locale":"it_IT","og_type":"article","og_title":"Accoglienza nelle nostre strutture - Suore di Loreto","og_description":"Accogliere, vivere e trasmettere l\u2019Amore per accompagnare la crescita di ciascuno in et\u00e0, sapienza e grazia. (n. 2 Cost.) Le nostre case sono aperte per accogliere tutti coloro che vogliono ritagliarsi una sosta godendo sia dei benefici del clima marittimo che delle passeggiate tra la natura. Distensione, riflessione, divertimento e cultura sono il cocktail che...","og_url":"https:\/\/www.suorediloreto.it\/lor\/le-attivita-2\/accoglienza-nelle-nostre-strutture\/","og_site_name":"Suore di Loreto","article_modified_time":"2021-01-05T16:09:35+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.suorediloreto.it\/lor\/le-attivita-2\/accoglienza-nelle-nostre-strutture\/","url":"https:\/\/www.suorediloreto.it\/lor\/le-attivita-2\/accoglienza-nelle-nostre-strutture\/","name":"Accoglienza nelle nostre strutture - Suore di Loreto","isPartOf":{"@id":"https:\/\/www.suorediloreto.it\/lor\/#website"},"datePublished":"2020-06-19T12:24:33+00:00","dateModified":"2021-01-05T16:09:35+00:00","breadcrumb":{"@id":"https:\/\/www.suorediloreto.it\/lor\/le-attivita-2\/accoglienza-nelle-nostre-strutture\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suorediloreto.it\/lor\/le-attivita-2\/accoglienza-nelle-nostre-strutture\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.suorediloreto.it\/lor\/le-attivita-2\/accoglienza-nelle-nostre-strutture\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.suorediloreto.it\/lor\/"},{"@type":"ListItem","position":2,"name":"Le attivit\u00e0","item":"https:\/\/www.suorediloreto.it\/lor\/le-attivita-2\/"},{"@type":"ListItem","position":3,"name":"Accoglienza nelle nostre strutture"}]},{"@type":"WebSite","@id":"https:\/\/www.suorediloreto.it\/lor\/#website","url":"https:\/\/www.suorediloreto.it\/lor\/","name":"Suore di Loreto","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suorediloreto.it\/lor\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.suorediloreto.it\/lor\/wp-json\/wp\/v2\/pages\/5267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.suorediloreto.it\/lor\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.suorediloreto.it\/lor\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.suorediloreto.it\/lor\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suorediloreto.it\/lor\/wp-json\/wp\/v2\/comments?post=5267"}],"version-history":[{"count":2,"href":"https:\/\/www.suorediloreto.it\/lor\/wp-json\/wp\/v2\/pages\/5267\/revisions"}],"predecessor-version":[{"id":5440,"href":"https:\/\/www.suorediloreto.it\/lor\/wp-json\/wp\/v2\/pages\/5267\/revisions\/5440"}],"up":[{"embeddable":true,"href":"https:\/\/www.suorediloreto.it\/lor\/wp-json\/wp\/v2\/pages\/4820"}],"wp:attachment":[{"href":"https:\/\/www.suorediloreto.it\/lor\/wp-json\/wp\/v2\/media?parent=5267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}