{"id":6933,"date":"2024-02-02T21:40:14","date_gmt":"2024-02-02T20:40:14","guid":{"rendered":"https:\/\/www.suorediloreto.it\/lor\/?p=6933"},"modified":"2024-02-02T21:40:14","modified_gmt":"2024-02-02T20:40:14","slug":"madre-natalina-e-il-territorio-vercellese","status":"publish","type":"post","link":"https:\/\/www.suorediloreto.it\/lor\/2024\/02\/02\/madre-natalina-e-il-territorio-vercellese\/","title":{"rendered":"Madre Natalina e il territorio Vercellese"},"content":{"rendered":"<p>Sabato 3 febbraio 2024, a S.Antonino di Saluggia, vi aspettiamo per condividere la gioia di un&#8217;amicizia comune: Madre Natalina.<\/p>\n<p>ore 17,00 S.Messa<\/p>\n<p>ore 18,00 proiezione docu-film<\/p>\n<p>saluti in convivialit\u00e0<\/p>\n<p>Non mancare!!!!!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sabato 3 febbraio 2024, a S.Antonino di Saluggia, vi aspettiamo per condividere la gioia di un&#8217;amicizia comune: Madre Natalina. ore 17,00 S.Messa ore 18,00 proiezione docu-film saluti in convivialit\u00e0 Non mancare!!!!!<\/p>\n","protected":false},"author":3,"featured_media":6934,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ghostkit_customizer_options":"","ghostkit_custom_css":"","ghostkit_custom_js_head":"","ghostkit_custom_js_foot":"","ghostkit_typography":"","_vp_format_video_url":"","_vp_image_focal_point":[],"footnotes":""},"categories":[32],"tags":[],"class_list":["post-6933","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultime-notizie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Madre Natalina e il territorio Vercellese - Suore di Loreto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suorediloreto.it\/lor\/2024\/02\/02\/madre-natalina-e-il-territorio-vercellese\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Madre Natalina e il territorio Vercellese - Suore di Loreto\" \/>\n<meta property=\"og:description\" content=\"Sabato 3 febbraio 2024, a S.Antonino di Saluggia, vi aspettiamo per condividere la gioia di un&#8217;amicizia comune: Madre Natalina. ore 17,00 S.Messa ore 18,00 proiezione docu-film saluti in convivialit\u00e0 Non mancare!!!!!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suorediloreto.it\/lor\/2024\/02\/02\/madre-natalina-e-il-territorio-vercellese\/\" \/>\n<meta property=\"og:site_name\" content=\"Suore di Loreto\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-02T20:40:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.suorediloreto.it\/lor\/wp-content\/uploads\/2024\/02\/Presentazione-S-Antonino-3-febbraio-2024.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"bruna\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"bruna\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suorediloreto.it\/lor\/2024\/02\/02\/madre-natalina-e-il-territorio-vercellese\/\",\"url\":\"https:\/\/www.suorediloreto.it\/lor\/2024\/02\/02\/madre-natalina-e-il-territorio-vercellese\/\",\"name\":\"Madre Natalina e il territorio Vercellese - Suore di Loreto\",\"isPartOf\":{\"@id\":\"https:\/\/www.suorediloreto.it\/lor\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suorediloreto.it\/lor\/2024\/02\/02\/madre-natalina-e-il-territorio-vercellese\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suorediloreto.it\/lor\/2024\/02\/02\/madre-natalina-e-il-territorio-vercellese\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.suorediloreto.it\/lor\/wp-content\/uploads\/2024\/02\/Presentazione-S-Antonino-3-febbraio-2024.jpg\",\"datePublished\":\"2024-02-02T20:40:14+00:00\",\"author\":{\"@id\":\"https:\/\/www.suorediloreto.it\/lor\/#\/schema\/person\/f2900e078903cfbc1e63c1d7239d618c\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.suorediloreto.it\/lor\/2024\/02\/02\/madre-natalina-e-il-territorio-vercellese\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suorediloreto.it\/lor\/2024\/02\/02\/madre-natalina-e-il-territorio-vercellese\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.suorediloreto.it\/lor\/2024\/02\/02\/madre-natalina-e-il-territorio-vercellese\/#primaryimage\",\"url\":\"https:\/\/www.suorediloreto.it\/lor\/wp-content\/uploads\/2024\/02\/Presentazione-S-Antonino-3-febbraio-2024.jpg\",\"contentUrl\":\"https:\/\/www.suorediloreto.it\/lor\/wp-content\/uploads\/2024\/02\/Presentazione-S-Antonino-3-febbraio-2024.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suorediloreto.it\/lor\/2024\/02\/02\/madre-natalina-e-il-territorio-vercellese\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.suorediloreto.it\/lor\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Madre Natalina e il territorio Vercellese\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suorediloreto.it\/lor\/#website\",\"url\":\"https:\/\/www.suorediloreto.it\/lor\/\",\"name\":\"Suore di Loreto\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suorediloreto.it\/lor\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suorediloreto.it\/lor\/#\/schema\/person\/f2900e078903cfbc1e63c1d7239d618c\",\"name\":\"bruna\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.suorediloreto.it\/lor\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9253566f02219ab869c7cf381828dc9ad61cd1c7070eb183a2266571d06eb383?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9253566f02219ab869c7cf381828dc9ad61cd1c7070eb183a2266571d06eb383?s=96&d=mm&r=g\",\"caption\":\"bruna\"},\"url\":\"https:\/\/www.suorediloreto.it\/lor\/author\/bruna\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Madre Natalina e il territorio Vercellese - Suore di Loreto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suorediloreto.it\/lor\/2024\/02\/02\/madre-natalina-e-il-territorio-vercellese\/","og_locale":"it_IT","og_type":"article","og_title":"Madre Natalina e il territorio Vercellese - Suore di Loreto","og_description":"Sabato 3 febbraio 2024, a S.Antonino di Saluggia, vi aspettiamo per condividere la gioia di un&#8217;amicizia comune: Madre Natalina. ore 17,00 S.Messa ore 18,00 proiezione docu-film saluti in convivialit\u00e0 Non mancare!!!!!","og_url":"https:\/\/www.suorediloreto.it\/lor\/2024\/02\/02\/madre-natalina-e-il-territorio-vercellese\/","og_site_name":"Suore di Loreto","article_published_time":"2024-02-02T20:40:14+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.suorediloreto.it\/lor\/wp-content\/uploads\/2024\/02\/Presentazione-S-Antonino-3-febbraio-2024.jpg","type":"image\/jpeg"}],"author":"bruna","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"bruna","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.suorediloreto.it\/lor\/2024\/02\/02\/madre-natalina-e-il-territorio-vercellese\/","url":"https:\/\/www.suorediloreto.it\/lor\/2024\/02\/02\/madre-natalina-e-il-territorio-vercellese\/","name":"Madre Natalina e il territorio Vercellese - Suore di Loreto","isPartOf":{"@id":"https:\/\/www.suorediloreto.it\/lor\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suorediloreto.it\/lor\/2024\/02\/02\/madre-natalina-e-il-territorio-vercellese\/#primaryimage"},"image":{"@id":"https:\/\/www.suorediloreto.it\/lor\/2024\/02\/02\/madre-natalina-e-il-territorio-vercellese\/#primaryimage"},"thumbnailUrl":"https:\/\/www.suorediloreto.it\/lor\/wp-content\/uploads\/2024\/02\/Presentazione-S-Antonino-3-febbraio-2024.jpg","datePublished":"2024-02-02T20:40:14+00:00","author":{"@id":"https:\/\/www.suorediloreto.it\/lor\/#\/schema\/person\/f2900e078903cfbc1e63c1d7239d618c"},"breadcrumb":{"@id":"https:\/\/www.suorediloreto.it\/lor\/2024\/02\/02\/madre-natalina-e-il-territorio-vercellese\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suorediloreto.it\/lor\/2024\/02\/02\/madre-natalina-e-il-territorio-vercellese\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.suorediloreto.it\/lor\/2024\/02\/02\/madre-natalina-e-il-territorio-vercellese\/#primaryimage","url":"https:\/\/www.suorediloreto.it\/lor\/wp-content\/uploads\/2024\/02\/Presentazione-S-Antonino-3-febbraio-2024.jpg","contentUrl":"https:\/\/www.suorediloreto.it\/lor\/wp-content\/uploads\/2024\/02\/Presentazione-S-Antonino-3-febbraio-2024.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.suorediloreto.it\/lor\/2024\/02\/02\/madre-natalina-e-il-territorio-vercellese\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.suorediloreto.it\/lor\/"},{"@type":"ListItem","position":2,"name":"Madre Natalina e il territorio Vercellese"}]},{"@type":"WebSite","@id":"https:\/\/www.suorediloreto.it\/lor\/#website","url":"https:\/\/www.suorediloreto.it\/lor\/","name":"Suore di Loreto","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suorediloreto.it\/lor\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.suorediloreto.it\/lor\/#\/schema\/person\/f2900e078903cfbc1e63c1d7239d618c","name":"bruna","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.suorediloreto.it\/lor\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9253566f02219ab869c7cf381828dc9ad61cd1c7070eb183a2266571d06eb383?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9253566f02219ab869c7cf381828dc9ad61cd1c7070eb183a2266571d06eb383?s=96&d=mm&r=g","caption":"bruna"},"url":"https:\/\/www.suorediloreto.it\/lor\/author\/bruna\/"}]}},"_links":{"self":[{"href":"https:\/\/www.suorediloreto.it\/lor\/wp-json\/wp\/v2\/posts\/6933","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.suorediloreto.it\/lor\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suorediloreto.it\/lor\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suorediloreto.it\/lor\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suorediloreto.it\/lor\/wp-json\/wp\/v2\/comments?post=6933"}],"version-history":[{"count":1,"href":"https:\/\/www.suorediloreto.it\/lor\/wp-json\/wp\/v2\/posts\/6933\/revisions"}],"predecessor-version":[{"id":6935,"href":"https:\/\/www.suorediloreto.it\/lor\/wp-json\/wp\/v2\/posts\/6933\/revisions\/6935"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suorediloreto.it\/lor\/wp-json\/wp\/v2\/media\/6934"}],"wp:attachment":[{"href":"https:\/\/www.suorediloreto.it\/lor\/wp-json\/wp\/v2\/media?parent=6933"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suorediloreto.it\/lor\/wp-json\/wp\/v2\/categories?post=6933"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suorediloreto.it\/lor\/wp-json\/wp\/v2\/tags?post=6933"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}